{"id":8345,"date":"2026-07-16T12:00:02","date_gmt":"2026-07-16T11:00:02","guid":{"rendered":"https:\/\/www.medtrips.co.uk\/electives-for-australian-medical-students-2\/"},"modified":"2026-07-24T13:48:19","modified_gmt":"2026-07-24T12:48:19","slug":"electives-for-australian-medical-students","status":"publish","type":"page","link":"https:\/\/www.medtrips.co.uk\/it\/electives-for-australian-medical-students\/","title":{"rendered":"Tirocini medici all&#8217;estero per studenti di medicina australiani"},"content":{"rendered":"<div style=\"max-width:1000px;margin:0 auto;padding:0 16px\">\n<div style=\"background:#005184;color:#fff;padding:48px 32px;border-radius:12px;text-align:center;margin:8px 0 32px\">\n<div style=\"display:inline-block;padding:5px 12px;border-radius:20px;font-size:12px;font-weight:500;margin-bottom:14px;letter-spacing:.02em\"> Per gli studenti di medicina australiani<\/div>\n<h2 style=\"color:#fff;font-size:34px;line-height:1.2;margin:0 0 12px;font-weight:600\" class=\"au-hero-h2\"> Tirocini medici all&#039;estero per studenti di medicina australiani<\/h2>\n<p style=\"color:#cce9f3;font-size:17px;line-height:1.5;margin:0 auto 22px;max-width:640px\"> Sono aperte le iscrizioni per i tirocini estivi da novembre a febbraio 2027. Durata: da 1 a 12 settimane, in 12 paesi, con supporto dell&#039;approvazione universitaria. Prezzi in dollari australiani (AUD).<\/p>\n<div style=\"margin:26px 0 6px\"> <a href=\"https:\/\/www.medtrips.co.uk\/it\/contact\/\" style=\"display:inline-block;background:#ffffff;color:#005184;font-weight:600;font-size:16px;padding:15px 32px;border-radius:8px;text-decoration:none\">Richiedi informazioni sul tuo corso opzionale<\/a><\/p>\n<div style=\"font-size:14px;color:#eaf1f6;margin-top:12px\"> Domande su date, paesi o costi? Il nostro team risponde entro 24 ore. \u00b7 <a href=\"https:\/\/www.medtrips.co.uk\/it\/prices\/\" style=\"color:#ffffff;text-decoration:underline\">Visualizza i prezzi in AUD<\/a><\/div>\n<\/div>\n<p> <a href=\"\/destinations\/\" style=\"display:inline-block;background:#32cdea;color:#0a3a52;font-weight:600;padding:12px 24px;border-radius:6px;text-decoration:none;font-size:14px;margin:4px\">Scopri le destinazioni<\/a> <a href=\"https:\/\/wa.me\/447424362742\" style=\"display:inline-block;background:#ffffff;color:#005184;font-weight:600;padding:12px 24px;border-radius:6px;text-decoration:none;font-size:14px;margin:4px\">Contattaci su WhatsApp<\/a> <\/div>\n<div style=\"display:grid;grid-template-columns:repeat(auto-fit,minmax(210px,1fr));gap:16px;margin:0 0 40px\">\n<div style=\"background:#e9f3f8;padding:20px 22px;border-radius:12px\">\n<div style=\"font-size:22px;font-weight:600;color:#005184;line-height:1.15\"> 3.200<\/div>\n<div style=\"font-size:13px;color:#0a3a52;font-weight:500;margin-top:2px\"> studenti di medicina collocati dal 2007<\/div>\n<p style=\"font-size:13px;color:#46535a;margin:10px 0 0;line-height:1.5\"> Dal team che ha creato Volunteering Solutions: quasi vent&#039;anni di esperienza in tirocini ospedalieri supervisionati all&#039;estero. <\/p>\n<\/div>\n<div style=\"background:#e9f3f8;padding:20px 22px;border-radius:12px\">\n<div style=\"font-size:22px;font-weight:600;color:#005184;line-height:1.15\"> Approvazione dell&#039;universit\u00e0<\/div>\n<div style=\"font-size:13px;color:#0a3a52;font-weight:500;margin-top:2px\"> supportato<\/div>\n<p style=\"font-size:13px;color:#46535a;margin:10px 0 0;line-height:1.5\"> Nomina del supervisore del consulente, ambito di competenza e documentazione restituiti entro 3 giorni lavorativi. <\/p>\n<\/div>\n<div style=\"background:#e9f3f8;padding:20px 22px;border-radius:12px\">\n<div style=\"font-size:22px;font-weight:600;color:#005184;line-height:1.15\"> Assicurazione<\/div>\n<div style=\"font-size:13px;color:#0a3a52;font-weight:500;margin-top:2px\"> incluso<\/div>\n<p style=\"font-size:13px;color:#46535a;margin:10px 0 0;line-height:1.5\"> Assicurazione medica inclusa nel prezzo. Politica di prenotazione flessibile. Certificazione B Corp. <\/p>\n<\/div>\n<div style=\"background:#e9f3f8;padding:20px 22px;border-radius:12px\">\n<div style=\"font-size:22px;font-weight:600;color:#005184;line-height:1.15\"> 24 ore su 24, 7 giorni su 7<\/div>\n<div style=\"font-size:13px;color:#0a3a52;font-weight:500;margin-top:2px\"> coordinatore locale<\/div>\n<p style=\"font-size:13px;color:#46535a;margin:10px 0 0;line-height:1.5\"> Coordinatori locali presenti in loco in ogni destinazione, oltre a una linea di emergenza attiva durante il vostro soggiorno.<\/p>\n<\/div>\n<\/div>\n<h2> Pianificazione del tuo tirocinio elettivo in Australia<\/h2>\n<p> Le facolt\u00e0 di medicina australiane chiudono per l&#039;estate tra met\u00e0 novembre e febbraio, ovvero durante il periodo di punta per i tirocini elettivi a livello mondiale. Gli ospedali si riempiono rapidamente per il periodo estivo, quindi consigliamo di confermare la propria iscrizione entro <strong>il 15 settembre<\/strong> per assicurarsi la destinazione, le date e la specializzazione preferite. Le settimane di inizio pi\u00f9 gettonate sono fine novembre, inizio dicembre e met\u00e0 gennaio.<\/p>\n<h2> Approvazione universitaria: ci occupiamo noi delle pratiche burocratiche.<\/h2>\n<p> Ogni facolt\u00e0 di medicina australiana gestisce autonomamente la propria procedura di approvazione dei tirocini elettivi (Melbourne, Sydney, UNSW, Monash, Adelaide, UQ, JCU, Notre Dame, Wollongong, Deakin, Newcastle, Flinders, Griffith, Bond, Curtin, Macquarie, WSU, Tasmania, ANU). Forniamo tutto il necessario all&#039;ufficio tirocini elettivi della vostra universit\u00e0:<\/p>\n<ul>\n<li> Lettera di conferma dell&#039;ospedale ospitante con indicazione del supervisore del consulente.<\/li>\n<li> Documento <a href=\"https:\/\/www.medtrips.co.uk\/it\/medical-elective-scope-of-practice\/\">relativo all&#039;ambito di attivit\u00e0<\/a> del programma<\/li>\n<li> Riepilogo delle assicurazioni e delle indennit\u00e0<\/li>\n<li> Accordo di tirocinio elettivo firmato<\/li>\n<li> CV\/qualifiche del supervisore disponibili su richiesta.<\/li>\n<\/ul>\n<p> Inviaci il modulo per i corsi opzionali della tua universit\u00e0 e lo compileremo e ti restituiremo entro tre giorni lavorativi. Tutti i dettagli sono disponibili sulla nostra <a href=\"https:\/\/www.medtrips.co.uk\/it\/medical-elective-sign-off\/\">pagina di approvazione<\/a> .<\/p>\n<h2 style=\"margin-top:40px\"> Destinazioni popolari per gli studenti australiani<\/h2>\n<p> Ogni destinazione \u00e8 gestita da un team locale esperto con cui collaboriamo da anni.<\/p>\n<div style=\"display:grid;grid-template-columns:repeat(auto-fit,minmax(220px,1fr));gap:14px;margin:16px 0 20px\"><a href=\"https:\/\/www.medtrips.co.uk\/pt-br\/destinations\/sri-lanka\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/2603_dsc_0231.jpg?v=20260826\" alt=\"Sri Lanka\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Sri Lanka<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Asia<\/span><\/span><\/a><a href=\"https:\/\/www.medtrips.co.uk\/pt-br\/destinations\/greece\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/2646_11_28129.jpg?v=20260826\" alt=\"Gr\u00e9cia\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Gr\u00e9cia<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Europa<\/span><\/span><\/a><a href=\"https:\/\/www.medtrips.co.uk\/pt-br\/destinations\/morocco\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/IMG-20241125-WA0058_0-768x603.jpg?v=20260826\" alt=\"Marrocos\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Marrocos<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Africa<\/span><\/span><\/a><a href=\"https:\/\/www.medtrips.co.uk\/pt-br\/destinations\/cambodia\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/429559187_803151028518054_1734357529910701441_n-768x653.jpg?v=20260826\" alt=\"Cambodia\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Cambodia<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Asia<\/span><\/span><\/a><a href=\"https:\/\/www.medtrips.co.uk\/pt-br\/destinations\/vietnam\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/IMG_4858_0-768x648.jpg?v=20260826\" alt=\"Vietnam\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Vietnam<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Asia<\/span><\/span><\/a><a href=\"https:\/\/www.medtrips.co.uk\/pt-br\/destinations\/tanzania\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/WhatsApp20Image202024-12-2020at2020.51.53_b1258466-768x512.jpg?v=20260826\" alt=\"Tanzania\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Tanzania<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Africa<\/span><\/span><\/a><a href=\"https:\/\/www.medtrips.co.uk\/pt-br\/destinations\/kenya\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/IMG-20250825-WA0016_0-768x576.jpg?v=20260826\" alt=\"Kenya\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Kenya<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Africa<\/span><\/span><\/a><a href=\"https:\/\/www.medtrips.co.uk\/ko\/destinations\/greece\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/2646_11_28129.jpg?v=20260826\" alt=\"Greece\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Greece<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Europe<\/span><\/span><\/a><a href=\"https:\/\/www.medtrips.co.uk\/ko\/destinations\/morocco\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/IMG-20241125-WA0058_0-768x603.jpg?v=20260826\" alt=\"Morocco\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Morocco<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Africa<\/span><\/span><\/a><a href=\"https:\/\/www.medtrips.co.uk\/fr\/destinations\/greece\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/2646_11_28129.jpg?v=20260826\" alt=\"Gr\u00e8ce\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Gr\u00e8ce<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Europe<\/span><\/span><\/a><a href=\"https:\/\/www.medtrips.co.uk\/fr\/destinations\/morocco\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/IMG-20241125-WA0058_0-768x603.jpg?v=20260826\" alt=\"Maroc\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Maroc<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Africa<\/span><\/span><\/a><a href=\"https:\/\/www.medtrips.co.uk\/fr\/destinations\/cambodia\/\" style=\"display:block;position:relative;border-radius:12px;overflow:hidden;text-decoration:none;color:#fff;aspect-ratio:4\/3;background:#0a3a52\"><img decoding=\"async\" src=\"https:\/\/www.medtrips.co.uk\/wp-content\/uploads\/2026\/06\/429559187_803151028518054_1734357529910701441_n-768x653.jpg?v=20260826\" alt=\"Cambodge\" loading=\"lazy\" style=\"width:100%;height:100%;object-fit:cover;display:block\"><span style=\"position:absolute;inset:0;background:linear-gradient(0deg,rgba(6,49,73,.85) 0%,rgba(6,49,73,.15) 55%,transparent 100%)\"><\/span><span style=\"position:absolute;left:14px;right:14px;bottom:12px\"><b style=\"display:block;font-size:17px;font-weight:600;line-height:1.2\">Cambodge<\/b><span style=\"display:block;font-size:12px;opacity:.9;margin-top:2px\">Asia<\/span><\/span><\/a><\/div>\n<p style=\"text-align:center\"> <a href=\"\/destinations\/\" style=\"display:inline-block;background:transparent;color:#005184;font-weight:500;padding:10px 20px;border:1px solid #005184;border-radius:6px;text-decoration:none;font-size:14px\">Tutte le 12 destinazioni \u2192<\/a><\/p>\n<h2 style=\"margin-top:40px\"> Durata degli incarichi: da 1 a 12 settimane<\/h2>\n<p> La tua vacanza estiva in Australia dura fino a 12 settimane. La maggior parte degli studenti sceglie un soggiorno di 4-8 settimane per avere tempo da dedicare al viaggio; alcuni optano per un mini-corso elettivo di 1-2 settimane all&#039;interno di un viaggio pi\u00f9 lungo. Puoi prolungare o accorciare il soggiorno di settimana in settimana al momento della prenotazione e combinare specializzazioni in due destinazioni diverse per un&#039;esperienza pi\u00f9 completa.<\/p>\n<h2> Prezzi in AUD<\/h2>\n<p> Ogni prezzo su Med Trips viene convertito in tempo reale in dollari australiani e aggiornato quotidianamente. Un piccolo acconto di prenotazione garantisce la prenotazione; il saldo \u00e8 dovuto 45 giorni prima dell&#039;inizio. Dall&#039;Australia si accettano bonifici bancari, pagamenti con carta e PayPal, oppure \u00e8 possibile suddividere il saldo in <strong>rate a tasso zero<\/strong> .<\/p>\n<h2> Cosa \u00e8 incluso<\/h2>\n<ul>\n<li> Tirocinio presso un ospedale universitario con un consulente supervisore designato.<\/li>\n<li> Servizio di prelievo in aeroporto e orientamento in loco.<\/li>\n<li> Alloggio: camera singola, pasti, WiFi<\/li>\n<li> Servizio di coordinamento locale attivo 24 ore su 24, 7 giorni su 7, e linea di emergenza.<\/li>\n<li> assicurazione medica<\/li>\n<li> Certificato di completamento degli studi di medicina<\/li>\n<\/ul>\n<h2 style=\"margin-top:40px\"> Domande frequenti <\/h2>\n<details style=\"border-bottom:1px solid #e7f1f4;padding:14px 0\">\n<summary style=\"font-weight:600;color:#0a3a52;cursor:pointer\"> Ho bisogno dell&#039;approvazione di MDANZ per svolgere un tirocinio elettivo all&#039;estero?<\/summary>\n<p style=\"margin:8px 0 0\"> No. L&#039;approvazione di MDANZ si applica ai tirocini presso gli ospedali australiani. I tirocini elettivi all&#039;estero sono approvati dal coordinatore dei tirocini elettivi della tua facolt\u00e0 di medicina. <\/p>\n<\/details>\n<details style=\"border-bottom:1px solid #e7f1f4;padding:14px 0\">\n<summary style=\"font-weight:600;color:#0a3a52;cursor:pointer\"> Questo varr\u00e0 come ore di tirocinio clinico?<\/summary>\n<p style=\"margin:8px 0 0\"> La maggior parte delle facolt\u00e0 di medicina australiane riconosce i tirocini elettivi svolti all&#039;estero di quattro settimane o pi\u00f9 ai fini del calcolo delle ore cliniche. Prima di prenotare, contatta l&#039;ufficio tirocini della tua universit\u00e0: ti forniremo tutta la documentazione necessaria. <\/p>\n<\/details>\n<details style=\"border-bottom:1px solid #e7f1f4;padding:14px 0\">\n<summary style=\"font-weight:600;color:#0a3a52;cursor:pointer\"> E per quanto riguarda l&#039;assicurazione di responsabilit\u00e0 professionale medica?<\/summary>\n<p style=\"margin:8px 0 0\"> La polizza di assicurazione per responsabilit\u00e0 professionale (PII) della tua facolt\u00e0 di medicina australiana di solito copre anche i tirocini elettivi all&#039;estero, ma verifica sempre la formulazione. Possiamo organizzare una copertura integrativa se necessario. <\/p>\n<\/details>\n<details style=\"border-bottom:1px solid #e7f1f4;padding:14px 0\">\n<summary style=\"font-weight:600;color:#0a3a52;cursor:pointer\"> Ho bisogno di un visto?<\/summary>\n<p style=\"margin:8px 0 0\"> Per la maggior parte delle nostre destinazioni \u00e8 possibile ottenere il visto all&#039;arrivo o il visto elettronico per i titolari di passaporto australiano. Vi invieremo istruzioni precise una volta che avrete scelto il Paese. <\/p>\n<\/details>\n<details style=\"border-bottom:1px solid #e7f1f4;padding:14px 0\">\n<summary style=\"font-weight:600;color:#0a3a52;cursor:pointer\"> Posso andare con un amico della facolt\u00e0 di medicina?<\/summary>\n<p style=\"margin:8px 0 0\"> S\u00ec, molti programmi di alloggio accolgono coppie o piccoli gruppi provenienti dalla stessa scuola. Prenotate insieme e condividete l&#039;alloggio. <\/p>\n<\/details>\n<details style=\"border-bottom:1px solid #e7f1f4;padding:14px 0\">\n<summary style=\"font-weight:600;color:#0a3a52;cursor:pointer\"> Quando dovrei prenotare?<\/summary>\n<p style=\"margin:8px 0 0\"> Entro il 15 settembre per un incarico da novembre a febbraio. Dopo tale data, le destinazioni e le specializzazioni pi\u00f9 richieste (pediatria, ostetricia e ginecologia, pronto soccorso) iniziano a esaurirsi. <\/p>\n<\/details>\n<div style=\"background:#005184;color:#fff;padding:36px 28px;border-radius:12px;text-align:center;margin:40px 0 24px\">\n<div style=\"font-size:22px;font-weight:600;margin-bottom:8px\"> Stai pianificando il tuo tirocinio estivo da novembre a febbraio 2027?<\/div>\n<p style=\"color:#cce9f3;margin:0 auto 22px;font-size:15px;max-width:560px\"> Prezzi in AUD \u00b7 Approvazione universitaria supportata \u00b7 Assicurazione medica inclusa \u00b7 Assistenza in loco 24 ore su 24, 7 giorni su 7<\/p>\n<p> <a href=\"https:\/\/wa.me\/447424362742\" style=\"display:inline-block;background:#32cdea;color:#0a3a52;font-weight:600;padding:12px 24px;border-radius:6px;text-decoration:none;font-size:14px;margin:4px\">Contattaci su WhatsApp<\/a> <a href=\"\/destinations\/\" style=\"display:inline-block;background:#ffffff;color:#005184;font-weight:600;padding:12px 24px;border-radius:6px;text-decoration:none;font-size:14px;margin:4px\">Visualizza tutte le destinazioni<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tirocini medici all&#8217;estero per studenti di medicina australiani. Da 1 a 12 settimane in 12 paesi, prezzi in AUD, con supporto per l&#8217;approvazione universitaria. Prenotazioni entro il 15 settembre per il periodo novembre-febbraio 2027.<\/p>\n","protected":false},"author":0,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8345","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medtrips.co.uk\/it\/wp-json\/wp\/v2\/pages\/8345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medtrips.co.uk\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.medtrips.co.uk\/it\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medtrips.co.uk\/it\/wp-json\/wp\/v2\/comments?post=8345"}],"version-history":[{"count":5,"href":"https:\/\/www.medtrips.co.uk\/it\/wp-json\/wp\/v2\/pages\/8345\/revisions"}],"predecessor-version":[{"id":8438,"href":"https:\/\/www.medtrips.co.uk\/it\/wp-json\/wp\/v2\/pages\/8345\/revisions\/8438"}],"wp:attachment":[{"href":"https:\/\/www.medtrips.co.uk\/it\/wp-json\/wp\/v2\/media?parent=8345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}